{"id":1988,"date":"2026-02-20T19:57:40","date_gmt":"2026-02-20T19:57:40","guid":{"rendered":"https:\/\/www.fittich.ch\/nos-partenaires\/"},"modified":"2026-05-20T08:49:20","modified_gmt":"2026-05-20T08:49:20","slug":"nos-partenaires","status":"publish","type":"page","link":"https:\/\/www.fittich.ch\/fr\/nos-partenaires\/","title":{"rendered":"Nos Partenaires"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1988\" class=\"elementor elementor-1988 elementor-707\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab09431 e-flex e-con-boxed e-con e-parent\" data-id=\"ab09431\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-38151c4 e-con-full banner_left e-flex e-con e-child\" data-id=\"38151c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4042f55 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"4042f55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nos Partenaires<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d89dfc elementor-widget__width-inherit elementor-widget elementor-widget-shortcode\" data-id=\"5d89dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><nav class=\"breadcrumbs\"><a href=\"https:\/\/www.fittich.ch\/fr\/\">Home<\/a><\/nav><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-092f3ad solution_sec e-flex e-con-boxed e-con e-parent\" data-id=\"092f3ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b3dbde elementor-widget__width-inherit elementor-widget elementor-widget-shortcode\" data-id=\"0b3dbde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n        <div class=\"partner_grid\">\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-14-1.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>VKF AEAI<\/h3>\n                    <p>L\u2019AEAI est : &#8211; L\u2019organisation fa\u00eeti\u00e8re des autorit\u00e9s cantonales de protection contre l\u2019incendie et des 19 institutions cantonales d\u2019assurance en Suisse &#8211; Le Centre suisse de protection contre l\u2019incendie d\u00e9sign\u00e9 par la Conf\u00e9d\u00e9ration et les Cantons pour un service de conseil en planification industrielle et de construction &#8211; Un bureau de conseil en technologies de la construction &#8211; Un organisme de certification pour les personnes accr\u00e9dit\u00e9es par la Conf\u00e9d\u00e9ration dans le domaine de la protection contre l\u2019incendie (selon la norme ISO\/CEI 17024\/2003)<\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-13.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>VdS<\/h3>\n                    <p>VdS est un organisme ind\u00e9pendant qui garantit depuis des d\u00e9cennies la s\u00e9curit\u00e9 et la fiabilit\u00e9 dans les secteurs de la protection incendie et de la s\u00e9curit\u00e9, en d\u00e9veloppant des concepts de s\u00e9curit\u00e9 avanc\u00e9s pour les plus grandes entreprises industrielles et commerciales, les principaux fabricants, ainsi que les entreprises sp\u00e9cialis\u00e9es et les professionnels du secteur. Ses bureaux d&rsquo;inspection technique, ses certifications VdS reconnues, ses laboratoires modernes et bien \u00e9quip\u00e9s, ainsi que son large \u00e9ventail de formations et de publications permettent \u00e0 VdS d&rsquo;offrir une gamme de services unique et de haute qualit\u00e9 qui contribue \u00e0 d\u00e9finir les normes internationales du secteur. <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-12.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>S\u00c9CURIT\u00c9 ACR\u00c9E<\/h3>\n                    <p>Fond\u00e9e en 2012, Acre a un objectif clair : assurer la s\u00e9curit\u00e9 des personnes et des biens dans un monde impr\u00e9visible. Pr\u00e9sente dans plus de 25 pays, Acre accompagne une client\u00e8le diversifi\u00e9e et joue un r\u00f4le cl\u00e9 dans le d\u00e9veloppement et la mise en \u0153uvre d\u2019initiatives mondiales en mati\u00e8re de technologies de s\u00e9curit\u00e9. Notre gamme compl\u00e8te de solutions de s\u00e9curit\u00e9, sur site et dans le cloud, r\u00e9pond \u00e0 tous vos besoins pour prot\u00e9ger vos actifs les plus pr\u00e9cieux. Du contr\u00f4le d\u2019acc\u00e8s physique \u00e0 la gestion des visiteurs, des alarmes anti-intrusion \u00e0 la transmission vid\u00e9o, nous concevons la solution id\u00e9ale pour vous.   <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"78\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-11-1-1.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>ANSUL<\/h3>\n                    <p>ANSUL est une marque mondiale haut de gamme de Tyco Fire Protection Products. Les produits de protection incendie sp\u00e9cialis\u00e9s d&rsquo;ANSUL sont con\u00e7us et fabriqu\u00e9s selon des normes rigoureuses et test\u00e9s sous la direction de laboratoires d&rsquo;essais et d&rsquo;organismes d&rsquo;agr\u00e9ment nationaux et internationaux ind\u00e9pendants.<\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-10.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>HANWHA TECHWIN<\/h3>\n                    <p>Hanwha Techwin (formerly Samsung Techwin) is a leading provider of video surveillance solutions for IP, analog video, and hybrid systems. Hanwha Techwin (anciennement Samsung Techwin) est un fournisseur de premier plan de solutions de vid\u00e9osurveillance pour les syst\u00e8mes IP, analogiques et hybrides. Fond\u00e9 en 1952, le groupe Hanwha est l&rsquo;un des dix premiers groupes d&rsquo;entreprises de Cor\u00e9e du Sud et une soci\u00e9t\u00e9 figurant au classement FORTUNE Global 500. Le groupe Hanwha compte 52 filiales \u00e0 l&rsquo;\u00e9chelle nationale et 146 partenaires dans le monde entier, r\u00e9partis dans trois grands secteurs : la fabrication et la construction, la finance, les services et les loisirs.<\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"93\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-9.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>SES<\/h3>\n                    <p>L&rsquo;Association suisse des fabricants de syst\u00e8mes de s\u00e9curit\u00e9 (SES) regroupe les principales entreprises suisses de ce secteur. Tous les membres de la SES s&rsquo;engagent \u00e0 respecter les nombreuses exigences de qualit\u00e9 et normes de s\u00e9curit\u00e9. Ils sont reconnus comme entreprises sp\u00e9cialis\u00e9es par l&rsquo;Association suisse d&rsquo;assurances (SIA) et\/ou l&rsquo;Association des \u00e9tablissements cantonaux d&rsquo;assurance incendie (AEAI).  <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Group-1597884214-1.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>SICK<\/h3>\n                    <p>SICK est l&rsquo;un des principaux fabricants mondiaux de capteurs et de solutions de d\u00e9tection pour applications industrielles. Fond\u00e9e en 1946, l&rsquo;entreprise, dont le si\u00e8ge social se trouve \u00e0 Waldkirch im Breisgau pr\u00e8s de Fribourg, est un leader technologique sur le march\u00e9. Avec plus de 50 filiales et de nombreux bureaux de repr\u00e9sentation, SICK est pr\u00e9sente dans le monde entier. Au cours de l&rsquo;exercice 2014, SICK employait environ 7 000 personnes dans le monde et a g\u00e9n\u00e9r\u00e9 un chiffre d&rsquo;affaires consolid\u00e9 de 1 099,8 millions d&rsquo;euros.   <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-8.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>SPRINX TECHNOLOGIES<\/h3>\n                    <p>Lorsque des professionnels d\u00e9cident de partager un chemin commun, en mettant en commun leurs connaissances et leur enthousiasme, naissent des entreprises qui, bien que relativement r\u00e9centes, proposent des solutions et des r\u00e9f\u00e9rences \u00e9prouv\u00e9es, enrichies par l\u2019innovation, fruit d\u2019une recherche technologique continue. C\u2019est l\u2019histoire de Sprinx Technologies, Spirit of Research and Innovation, une entreprise d\u2019ing\u00e9nierie et de d\u00e9veloppement de logiciels jeune et dynamique, sp\u00e9cialis\u00e9e dans la conception et la fourniture de solutions de vid\u00e9osurveillance et d\u2019analyse vid\u00e9o. <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-7.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>UTC<\/h3>\n                    <p>UTC Building &#038; Industrial Systems est le plus grand fournisseur mondial de technologies du b\u00e2timent. Les syst\u00e8mes UTC, tels que les ascenseurs, les escaliers m\u00e9caniques, la s\u00e9curit\u00e9 incendie, la s\u00fbret\u00e9, l\u2019automatisation des b\u00e2timents, le chauffage, la ventilation, la climatisation et la r\u00e9frig\u00e9ration, favorisent des b\u00e2timents int\u00e9gr\u00e9s et performants, plus s\u00fbrs, plus intelligents et plus durables. UTC Building &#038; Industrial Systems est une division de United Technologies Corp., un fournisseur de premier plan de syst\u00e8mes a\u00e9rospatiaux et de construction pour l\u2019industrie mondiale du b\u00e2timent.<\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"90\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-6.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>VIKING<\/h3>\n                    <p>Depuis plus de 80 ans, le nom Viking est un symbole de leadership en mati\u00e8re de protection incendie. Aujourd&rsquo;hui, les entreprises du groupe Viking proposent aux entrepreneurs ind\u00e9pendants de syst\u00e8mes d&rsquo;extinction automatique des solutions int\u00e9gr\u00e9es pour tous les types de besoins en protection incendie. Le groupe Viking offre : Qualit\u00e9 : Une attention constante \u00e0 l&rsquo;am\u00e9lioration continue, des produits que nous fabriquons aux services que nous proposons. \u00c9tendue : Des solutions pour chaque type de besoin sont disponibles aupr\u00e8s d&rsquo;une source unique. Support : Service client et support technique. Innovation : Les produits Viking sont con\u00e7us et mis en \u0153uvre en tenant compte des besoins des clients. Disponibilit\u00e9 : 44 sites appartenant \u00e0 l&rsquo;entreprise dans le monde entier.      <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-5-1.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>CISCO<\/h3>\n                    <p>Cisco est le leader mondial des technologies de l&rsquo;information, aidant les entreprises \u00e0 saisir les opportunit\u00e9s de demain en d\u00e9montrant que des choses extraordinaires peuvent se produire lorsque vous connectez ce qui ne l&rsquo;\u00e9tait pas auparavant \u2013 comme les cam\u00e9ras IP.<\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"90\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Group-1597884214.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>WINDOWMASTER<\/h3>\n                    <p>Fittich SA est le partenaire officiel de WindowMaster, sp\u00e9cialis\u00e9 dans le d\u00e9veloppement et la production de syst\u00e8mes intelligents d\u2019automatisation des fen\u00eatres, de syst\u00e8mes de d\u00e9senfumage et d\u2019\u00e9vacuation de chaleur (RWA), d\u2019automatisation de fa\u00e7ade et de ventilation naturelle. Les solutions et composants RWA ont \u00e9t\u00e9 test\u00e9s et approuv\u00e9s conform\u00e9ment aux normes EN, DIN et VdS reconnues. Par ailleurs, sous l\u2019appellation \u00ab ventilation naturelle contr\u00f4l\u00e9e \u00bb, WindowMaster propose des solutions de climat int\u00e9rieur hautement durables pour presque tous les types de b\u00e2timents, fond\u00e9es sur les \u00e9conomies de CO2 et l\u2019utilisation efficace de ressources naturelles telles que le vent et la pouss\u00e9e thermique.  <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-4.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>AVIGILON<\/h3>\n                    <p>Le portefeuille Avigilon de vid\u00e9osurveillance, d\u2019analyses avanc\u00e9es et de syst\u00e8mes de contr\u00f4le d\u2019acc\u00e8s intelligents fait partie de l\u2019\u00e9cosyst\u00e8me critique de Motorola Solutions, con\u00e7u pour la s\u00e9curit\u00e9 publique et celle des entreprises. Les solutions Avigilon vous aident \u00e0 trouver et \u00e0 partager des informations critiques plus rapidement, afin que vous puissiez r\u00e9pondre aux incidents avec la rapidit\u00e9 et la d\u00e9termination n\u00e9cessaires pour prot\u00e9ger les personnes, les op\u00e9rations et les actifs. La suite technologique de Motorola Solutions \u2014 s\u00e9curit\u00e9 vid\u00e9o, contr\u00f4le d\u2019acc\u00e8s et logiciels de centre de commandement \u2014 cr\u00e9e l\u2019\u00e9cosyst\u00e8me technologique le plus int\u00e9gr\u00e9 pour s\u00e9curiser les communaut\u00e9s et aider les entreprises \u00e0 rester productives et prot\u00e9g\u00e9es.  <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-3.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>HELUX<\/h3>\n                    <p>Expertise et qualit\u00e9 en \u00e9clairage de s\u00e9curit\u00e9. De nombreuses ann\u00e9es d&rsquo;exp\u00e9rience et des gammes de produits techniquement sophistiqu\u00e9es qui r\u00e9pondent aux normes les plus \u00e9lev\u00e9es font de Helux AG le partenaire num\u00e9ro un en mati\u00e8re d&rsquo;\u00e9clairage de s\u00e9curit\u00e9. Gr\u00e2ce \u00e0 des conseils personnalis\u00e9s et un service in\u00e9gal\u00e9, HELUX AG met syst\u00e9matiquement son expertise au service du client. Le r\u00e9sultat : des solutions sur mesure qui rel\u00e8vent tous les d\u00e9fis de l&rsquo;\u00e9clairage de s\u00e9curit\u00e9.   <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"partner_box\">\n\n                <div class=\"partner_img\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"96\" src=\"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/Rectangle-5101-2.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>                                    <\/div>\n\n                <div class=\"partner_content\">\n                    <h3>SALTO SYSTEMS<\/h3>\n                    <p>Salto est un leader mondial des solutions de contr\u00f4le d&rsquo;acc\u00e8s, membre de SALTO WECOSYSTEM. L&rsquo;entreprise propose des solutions innovantes, notamment des applications autonomes, cloud et mobiles. Ses produits de verrouillage \u00e9lectronique \u00e9tablissent de nouvelles normes en mati\u00e8re de s\u00e9curit\u00e9, de gestion, de flexibilit\u00e9 et de design, offrant des avantages concrets pour pratiquement tout type de porte.  <\/p>\n                <\/div>\n\n            <\/div>\n\n        \n        <\/div>\n\n    <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1988","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos Partenaires - Fittich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fittich.ch\/our-partners\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos Partenaires - Fittich\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fittich.ch\/our-partners\/\" \/>\n<meta property=\"og:site_name\" content=\"Fittich\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T08:49:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/our-partners\\\/\",\"url\":\"https:\\\/\\\/www.fittich.ch\\\/our-partners\\\/\",\"name\":\"Nos Partenaires - Fittich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#website\"},\"datePublished\":\"2026-02-20T19:57:40+00:00\",\"dateModified\":\"2026-05-20T08:49:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/our-partners\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fittich.ch\\\/our-partners\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/our-partners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fittich.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos Partenaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/\",\"name\":\"Fittich\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#organization\",\"name\":\"Fittich\",\"url\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fittich.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7f65969978b99c7bf514bab285bbf665b6716bc8.png\",\"contentUrl\":\"https:\\\/\\\/www.fittich.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7f65969978b99c7bf514bab285bbf665b6716bc8.png\",\"width\":770,\"height\":241,\"caption\":\"Fittich\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fittich.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos Partenaires - Fittich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fittich.ch\/our-partners\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos Partenaires - Fittich","og_url":"https:\/\/www.fittich.ch\/our-partners\/","og_site_name":"Fittich","article_modified_time":"2026-05-20T08:49:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fittich.ch\/our-partners\/","url":"https:\/\/www.fittich.ch\/our-partners\/","name":"Nos Partenaires - Fittich","isPartOf":{"@id":"https:\/\/www.fittich.ch\/fr\/#website"},"datePublished":"2026-02-20T19:57:40+00:00","dateModified":"2026-05-20T08:49:20+00:00","breadcrumb":{"@id":"https:\/\/www.fittich.ch\/our-partners\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fittich.ch\/our-partners\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fittich.ch\/our-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fittich.ch\/"},{"@type":"ListItem","position":2,"name":"Nos Partenaires"}]},{"@type":"WebSite","@id":"https:\/\/www.fittich.ch\/fr\/#website","url":"https:\/\/www.fittich.ch\/fr\/","name":"Fittich","description":"","publisher":{"@id":"https:\/\/www.fittich.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fittich.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fittich.ch\/fr\/#organization","name":"Fittich","url":"https:\/\/www.fittich.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fittich.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/7f65969978b99c7bf514bab285bbf665b6716bc8.png","contentUrl":"https:\/\/www.fittich.ch\/wp-content\/uploads\/2026\/02\/7f65969978b99c7bf514bab285bbf665b6716bc8.png","width":770,"height":241,"caption":"Fittich"},"image":{"@id":"https:\/\/www.fittich.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/pages\/1988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/comments?post=1988"}],"version-history":[{"count":0,"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/pages\/1988\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fittich.ch\/fr\/wp-json\/wp\/v2\/media?parent=1988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}